{"id":114,"count":1,"description":"","link":"http:\/\/www.lalunachevuoi.it\/blog\/tag\/colori-matrimonio\/","name":"colori matrimonio","slug":"colori-matrimonio","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.lalunachevuoi.it\/blog\/wp-json\/wp\/v2\/tags\/114"}],"collection":[{"href":"http:\/\/www.lalunachevuoi.it\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.lalunachevuoi.it\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.lalunachevuoi.it\/blog\/wp-json\/wp\/v2\/posts?tags=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}